{"id":12,"count":4,"description":"","link":"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/","name":"Bar agricolo","slug":"bar-agricolo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bar agricolo \u00b7 Journal \u00b7 Poggio ai Santi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bar agricolo \u00b7 Journal \u00b7 Poggio ai Santi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/\" \/>\n<meta property=\"og:site_name\" content=\"POGGIOAISANTI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/\",\"url\":\"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/\",\"name\":\"Bar agricolo \u00b7 Journal \u00b7 Poggio ai Santi\",\"isPartOf\":{\"@id\":\"https:\/\/poggioaisanti.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/poggioaisanti.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bar agricolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/poggioaisanti.com\/blog\/#website\",\"url\":\"https:\/\/poggioaisanti.com\/blog\/\",\"name\":\"POGGIOAISANTI\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/poggioaisanti.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bar agricolo \u00b7 Journal \u00b7 Poggio ai Santi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/","og_locale":"it_IT","og_type":"article","og_title":"Bar agricolo \u00b7 Journal \u00b7 Poggio ai Santi","og_url":"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/","og_site_name":"POGGIOAISANTI","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/","url":"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/","name":"Bar agricolo \u00b7 Journal \u00b7 Poggio ai Santi","isPartOf":{"@id":"https:\/\/poggioaisanti.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/poggioaisanti.com\/blog\/tag\/bar-agricolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poggioaisanti.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Bar agricolo"}]},{"@type":"WebSite","@id":"https:\/\/poggioaisanti.com\/blog\/#website","url":"https:\/\/poggioaisanti.com\/blog\/","name":"POGGIOAISANTI","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poggioaisanti.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/poggioaisanti.com\/blog\/wp-json\/wp\/v2\/tags\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poggioaisanti.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/poggioaisanti.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/poggioaisanti.com\/blog\/wp-json\/wp\/v2\/posts?tags=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}